{"id":231,"count":7,"description":"","link":"https:\/\/www.litelife.store\/en\/cat-prod\/pacchetti-regalo\/","name":"Gift card","slug":"pacchetti-regalo","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pacchetti regalo benessere, acquista online | Lite Life SPA<\/title>\n<meta name=\"description\" content=\"Fai un regalo speciale! Acquista online i pacchetti benessere di Lite Life, la spa pi\u00f9 grande di Napoli, da personalizzare come si desidera!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.litelife.store\/en\/cat-prod\/pacchetti-regalo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pacchetti regalo benessere, acquista online | Lite Life SPA\" \/>\n<meta property=\"og:description\" content=\"Fai un regalo speciale! Acquista online i pacchetti benessere di Lite Life, la spa pi\u00f9 grande di Napoli, da personalizzare come si desidera!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.litelife.store\/en\/cat-prod\/pacchetti-regalo\/\" \/>\n<meta property=\"og:site_name\" content=\"LiteLife Shop\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.litelife.store\/en\/wp-content\/uploads\/2019\/05\/lite-life.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.litelife.store\\\/en\\\/cat-prod\\\/pacchetti-regalo\\\/\",\"url\":\"https:\\\/\\\/www.litelife.store\\\/en\\\/cat-prod\\\/pacchetti-regalo\\\/\",\"name\":\"Pacchetti regalo benessere, acquista online | Lite Life SPA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.litelife.store\\\/en\\\/#website\"},\"description\":\"Fai un regalo speciale! Acquista online i pacchetti benessere di Lite Life, la spa pi\u00f9 grande di Napoli, da personalizzare come si desidera!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.litelife.store\\\/en\\\/cat-prod\\\/pacchetti-regalo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.litelife.store\\\/en\\\/cat-prod\\\/pacchetti-regalo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Life Life\",\"item\":\"https:\\\/\\\/www.litelife.store\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gift card\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.litelife.store\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.litelife.store\\\/en\\\/\",\"name\":\"LiteLife Shop\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.litelife.store\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.litelife.store\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.litelife.store\\\/en\\\/#organization\",\"name\":\"Lite Life\",\"url\":\"https:\\\/\\\/www.litelife.store\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.litelife.store\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.litelife.store\\\/en\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/logo_litelife_store.png\",\"contentUrl\":\"https:\\\/\\\/www.litelife.store\\\/en\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/logo_litelife_store.png\",\"width\":442,\"height\":213,\"caption\":\"Lite Life\"},\"image\":{\"@id\":\"https:\\\/\\\/www.litelife.store\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pacchetti regalo benessere, acquista online | Lite Life SPA","description":"Fai un regalo speciale! Acquista online i pacchetti benessere di Lite Life, la spa pi\u00f9 grande di Napoli, da personalizzare come si desidera!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.litelife.store\/en\/cat-prod\/pacchetti-regalo\/","og_locale":"en_US","og_type":"article","og_title":"Pacchetti regalo benessere, acquista online | Lite Life SPA","og_description":"Fai un regalo speciale! Acquista online i pacchetti benessere di Lite Life, la spa pi\u00f9 grande di Napoli, da personalizzare come si desidera!","og_url":"https:\/\/www.litelife.store\/en\/cat-prod\/pacchetti-regalo\/","og_site_name":"LiteLife Shop","og_image":[{"width":1200,"height":700,"url":"https:\/\/www.litelife.store\/en\/wp-content\/uploads\/2019\/05\/lite-life.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.litelife.store\/en\/cat-prod\/pacchetti-regalo\/","url":"https:\/\/www.litelife.store\/en\/cat-prod\/pacchetti-regalo\/","name":"Pacchetti regalo benessere, acquista online | Lite Life SPA","isPartOf":{"@id":"https:\/\/www.litelife.store\/en\/#website"},"description":"Fai un regalo speciale! Acquista online i pacchetti benessere di Lite Life, la spa pi\u00f9 grande di Napoli, da personalizzare come si desidera!","breadcrumb":{"@id":"https:\/\/www.litelife.store\/en\/cat-prod\/pacchetti-regalo\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.litelife.store\/en\/cat-prod\/pacchetti-regalo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Life Life","item":"https:\/\/www.litelife.store\/en\/"},{"@type":"ListItem","position":2,"name":"Gift card"}]},{"@type":"WebSite","@id":"https:\/\/www.litelife.store\/en\/#website","url":"https:\/\/www.litelife.store\/en\/","name":"LiteLife Shop","description":"","publisher":{"@id":"https:\/\/www.litelife.store\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.litelife.store\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.litelife.store\/en\/#organization","name":"Lite Life","url":"https:\/\/www.litelife.store\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.litelife.store\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.litelife.store\/en\/wp-content\/uploads\/2019\/05\/logo_litelife_store.png","contentUrl":"https:\/\/www.litelife.store\/en\/wp-content\/uploads\/2019\/05\/logo_litelife_store.png","width":442,"height":213,"caption":"Lite Life"},"image":{"@id":"https:\/\/www.litelife.store\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.litelife.store\/en\/wp-json\/wp\/v2\/product_cat\/231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.litelife.store\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.litelife.store\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.litelife.store\/en\/wp-json\/wp\/v2\/product?product_cat=231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}